{"id":6238,"date":"2019-09-20T16:24:37","date_gmt":"2019-09-20T14:24:37","guid":{"rendered":"https:\/\/icfrc.fr?page_id=6238"},"modified":"2025-03-24T14:15:45","modified_gmt":"2025-03-24T13:15:45","slug":"historique-et-missions","status":"publish","type":"page","link":"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/","title":{"rendered":"Historique et missions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6238\" class=\"elementor elementor-6238 elementor-5640\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f63b8e elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0f63b8e\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:7108,&quot;url&quot;:&quot;https:\\\/\\\/fondation-lehn.fr\\\/\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ISIS_2020_S-007-tiny.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2579041\" data-id=\"2579041\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaa668c elementor-widget elementor-widget-heading\" data-id=\"aaa668c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Historique et missions de la fondation<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c84f7da\" data-id=\"c84f7da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb5e798 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb5e798\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7b39c4\" data-id=\"f7b39c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3888558 elementor-widget elementor-widget-heading\" data-id=\"3888558\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Notre histoire<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27a81a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27a81a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e2b996\" data-id=\"2e2b996\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25ba6c0 elementor-widget elementor-widget-text-editor\" data-id=\"25ba6c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Le \u00ab Centre international de recherche aux fronti\u00e8res de la chimie \u00bb (CIRFC), encore appel\u00e9 Fondation pour la Recherche en Chimie puis Fondation Jean-Marie Lehn, a \u00e9t\u00e9 cr\u00e9\u00e9 en 2007 par l\u2019\u00c9tat pour soutenir le p\u00f4le d\u2019excellence en chimie \u00e0 Strasbourg, unique en France et reconnu \u00e0 l\u2019international : <span style=\"color: #ff6600;\">1er dans l\u2019Union Europ\u00e9enne selon le classement de Shanghai 2024<\/span>.<\/p><p>La fondation a \u00e9t\u00e9 mise en place \u00e0 l\u2019origine dans le cadre de l\u2019initiative du Minist\u00e8re de la recherche appel\u00e9e \u00ab R\u00e9seau th\u00e9matique de recherche avanc\u00e9e \u00bb (RTRA). Le statut juridique de fondation de coop\u00e9ration scientifique \u00e0 but non lucratif, de droit priv\u00e9 et reconnue d\u2019utilit\u00e9 publique, permet de recueillir des fonds d\u2019origine priv\u00e9e, pour soutenir les meilleures \u00e9quipes de l\u2019Universit\u00e9 de Strasbourg dans le domaine de la chimie et de ses interfaces avec la physique, la biologie et la m\u00e9decine. La cr\u00e9ation de la Fondation pour la Recherche en Chimie a \u00e9t\u00e9 une \u00e9tape de plus dans la longue tradition d\u2019excellence de la chimie strasbourgeoise.<\/p><p>En 2022, c&#8217;est avec une immense fiert\u00e9 que la Fondation pour la Recherche en Chimie a proc\u00e9d\u00e9\u00a0 \u00e0 un changement de nom pour devenir la Fondation Jean-Marie Lehn, en accord avec le\u00a0 prix Nobel de chimie Jean-Marie Lehn, Professeur \u00e0 l\u2019Universit\u00e9 de Strasbourg et chimiste de renomm\u00e9e mondiale.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fb2a5f\" data-id=\"1fb2a5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb6a887 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"fb6a887\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"785\" height=\"754\" src=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation.png\" class=\"attachment-full size-full wp-image-6921\" alt=\"\" srcset=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation.png 785w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation-300x288.png 300w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation-768x738.png 768w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation-600x576.png 600w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d6dc60 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d6dc60\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-421ea3e\" data-id=\"421ea3e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a66785 elementor-widget elementor-widget-heading\" data-id=\"3a66785\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Le mot du pr\u00e9sident<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8d8d77 elementor-widget elementor-widget-testimonial\" data-id=\"f8d8d77\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\u00ab \u00catre aux c\u00f4t\u00e9s des chercheurs et \u00e9tudiants chimistes de l\u2019Universit\u00e9 de Strasbourg et du CNRS est le seul but de la fondation qui apporte sa contribution, \u00e0 sa mani\u00e8re, au rayonnement international de la chimie strasbourgeoise. Son objectif est de permettre aux travaux de recherche les plus prometteurs d\u2019aboutir au plus vite et de concourir au d\u00e9veloppement d\u2019une recherche fran\u00e7aise innovante et pionni\u00e8re, porteuse de progr\u00e8s pour tous. \u00bb<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img width=\"400\" height=\"278\" src=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2014\/07\/BM5-horizontal2.jpg\" class=\"attachment-full size-full wp-image-1576\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Bernard MEUNIER<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Pr\u00e9sident de la Fondation Jean-Marie Lehn<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95e86f3 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"95e86f3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31d95ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31d95ba\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab945b9\" data-id=\"ab945b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3786b0c elementor-widget elementor-widget-heading\" data-id=\"3786b0c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Nos missions<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b590241 elementor-widget elementor-widget-image\" data-id=\"b590241\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"800\" height=\"332\" src=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-1024x425.png\" class=\"attachment-large size-large wp-image-6719\" alt=\"\" srcset=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-1024x425.png 1024w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-300x124.png 300w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-768x319.png 768w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-1536x637.png 1536w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-2048x850.png 2048w, https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/accueil-site-web-frc-600x249.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a1657a2\" data-id=\"a1657a2\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a606106 elementor-widget elementor-widget-text-editor\" data-id=\"a606106\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Selon la convention d\u2019engagement avec l\u2019\u00c9tat, la fondation a pour mission de :<\/p><ul><li>Renforcer, faire rayonner et dynamiser l\u2019excellence du p\u00f4le de recherche en chimie strasbourgeois.<\/li><li>Apporter des leviers pour faciliter les activit\u00e9s des chercheurs.<\/li><li>Faire rayonner les laboratoires aupr\u00e8s du monde socio-\u00e9conomique.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b6096c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b6096c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1af36a\" data-id=\"a1af36a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1594b9e elementor-widget elementor-widget-heading\" data-id=\"1594b9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Nos actions<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c31a2c9 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c31a2c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e72560\" data-id=\"9e72560\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7868bf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7868bf4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-62d6446\" data-id=\"62d6446\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac0f54 elementor-widget elementor-widget-heading\" data-id=\"cac0f54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Financer les recherches les plus innovantes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da5207f elementor-widget elementor-widget-text-editor\" data-id=\"da5207f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u2192 Un r\u00e9seau compos\u00e9 de <span style=\"color: #ff6600;\">80 \u00e9quipes de recherche<\/span> \u00e0 Strasbourg qui interagissent quotidiennement sur des sujets ambitieux dans le domaine de la chimie et de ses interfaces avec la biologie, la physique et la m\u00e9decine.<\/p><p>\u2192 <span style=\"color: #ff6600;\">Des programmes sur-mesure<\/span> de soutien \u00e0 la recherche (financement d&#8217;\u00e9quipements collectifs et de projets de recherche, mise en place de chaires d&#8217;excellence, attribution de prix et de\u00a0 subventions).<\/p><p>\u2192 Une grande exp\u00e9rience pour <span style=\"color: #000000;\">expertiser et financer les projets les plus ambitieux<\/span> avec le concours d&#8217;un <span style=\"color: #ff6600;\">conseil scientifique international et autonome<\/span> dans ses d\u00e9cisions.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ef1ad56\" data-id=\"ef1ad56\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7225c0a elementor-widget elementor-widget-heading\" data-id=\"7225c0a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">G\u00e9rer des fonds pour la communaut\u00e9 de chercheurs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75eb3ec elementor-widget elementor-widget-text-editor\" data-id=\"75eb3ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u2192 Un <span style=\"color: #ff6600;\">outil facilitateur<\/span> au service des chercheurs.<\/p><p>\u2192 Une <span style=\"color: #ff6600;\">gestion de fonds simplifi\u00e9e<\/span> gr\u00e2ce au statut de fondation priv\u00e9e, et r\u00e9guli\u00e8rement audit\u00e9e par les instances nationales et internationales.<\/p><p>\u2192 Une <span style=\"color: #ff6600;\">gestion stable<\/span> de la dotation qui permet de d\u00e9gager des fonds chaque ann\u00e9e pour la recherche.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-81c386c\" data-id=\"81c386c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20faa9d elementor-widget elementor-widget-heading\" data-id=\"20faa9d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Faire rayonner le p\u00f4le chimie de Strasbourg aupr\u00e8s du monde socio-\u00e9conomique<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d106963 elementor-widget elementor-widget-text-editor\" data-id=\"d106963\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u2192 Une <span style=\"color: #ff6600;\">interface essentielle<\/span> entre les mondes acad\u00e9mique et industriel cr\u00e9ant une dynamique d\u2019\u00e9changes entre universitaires et acteurs socio-\u00e9conomiques.<\/p><p>\u2192 Une <span style=\"color: #ff6600;\">porte d&#8217;entr\u00e9e<\/span> vers les laboratoires de chimie pour des <span style=\"color: #ff6600;\">partenariats sur-mesure avec les entreprises en m\u00e9c\u00e9nat.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eb250b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eb250b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea9c8fe\" data-id=\"ea9c8fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-490e93d elementor-widget elementor-widget-heading\" data-id=\"490e93d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Qui peut b\u00e9n\u00e9ficier des actions de la fondation ?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9243938 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9243938\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-033660f\" data-id=\"033660f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-273a37b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"273a37b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e992dc3\" data-id=\"e992dc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea183cf elementor-cta--layout-image-above elementor-cta--valign-top elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ea183cf\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLe r\u00e9seau de la fondation\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLa Fondation Jean-Marie Lehn forme un <b>r\u00e9seau<\/b> qui regroupe une s\u00e9lection de chercheurs de l'Universit\u00e9 de Strasbourg et du CNRS, approuv\u00e9e par le conseil scientifique et valid\u00e9e par le conseil d\u2019administration. Les programmes de soutien \u00e0 la recherche (financements d\u2019\u00e9quipements, de projets de recherche ou de subventions) sont accessibles <u>uniquement<\/u> aux chercheurs de ce r\u00e9seau.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/fondation-lehn.fr\/\/le-pole-et-les-laboratoires-de-recherche\/\">\n\t\t\t\t\t\tConsultez la liste des membres\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e775b1f\" data-id=\"e775b1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b58d3 elementor-cta--layout-image-above elementor-cta--valign-top elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"74b58d3\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLe r\u00e9seau \u00e9largi\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tLa Fondation Jean-Marie Lehn accompagne, pour le m\u00e9c\u00e9nat et l\u2019aide \u00e0 la gestion de fonds, un <b>r\u00e9seau \u00e9largi<\/b>, regroupant l\u2019ensemble des chercheurs strasbourgeois du domaine de la chimie, et ses fronti\u00e8res avec la biologie, la physique et la m\u00e9decine.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Historique et missions de la fondation Notre histoire Le \u00ab Centre international de recherche aux fronti\u00e8res de la chimie \u00bb (CIRFC), encore appel\u00e9 Fondation pour la Recherche en Chimie puis Fondation Jean-Marie Lehn, a \u00e9t\u00e9 cr\u00e9\u00e9 en 2007 par l\u2019\u00c9tat pour soutenir le p\u00f4le d\u2019excellence en chimie \u00e0 Strasbourg, unique en France et reconnu \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":65,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Historique et missions - Fondation Jean-Marie Lehn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historique et missions - Fondation Jean-Marie Lehn\" \/>\n<meta property=\"og:description\" content=\"Historique et missions de la fondation Notre histoire Le \u00ab Centre international de recherche aux fronti\u00e8res de la chimie \u00bb (CIRFC), encore appel\u00e9 Fondation pour la Recherche en Chimie puis Fondation Jean-Marie Lehn, a \u00e9t\u00e9 cr\u00e9\u00e9 en 2007 par l\u2019\u00c9tat pour soutenir le p\u00f4le d\u2019excellence en chimie \u00e0 Strasbourg, unique en France et reconnu \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Jean-Marie Lehn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fondation-pour-la-Recherche-en-Chimie-244345315919500\/?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T13:15:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Fondation_FRC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"3 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/#website\",\"url\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/\",\"name\":\"Fondation Jean-Marie Lehn\",\"description\":\"La Fondation accompagne le d\\u00e9veloppement du p\\u00f4le de recherche en chimie de l&#039;Universit\\u00e9 de Strasbourg et du CNRS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/dev2.jeremie-zipfel.fr\/wp-content\/uploads\/2020\/04\/genese-fondation.png\",\"width\":785,\"height\":754},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/#webpage\",\"url\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/\",\"name\":\"Historique et missions - Fondation Jean-Marie Lehn\",\"isPartOf\":{\"@id\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/#primaryimage\"},\"datePublished\":\"2019-09-20T14:24:37+00:00\",\"dateModified\":\"2025-03-24T13:15:45+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev2.jeremie-zipfel.fr\/en\/historique-et-missions\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/pages\/6238"}],"collection":[{"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/comments?post=6238"}],"version-history":[{"count":41,"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/pages\/6238\/revisions"}],"predecessor-version":[{"id":26021,"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/pages\/6238\/revisions\/26021"}],"wp:attachment":[{"href":"https:\/\/dev2.jeremie-zipfel.fr\/en\/wp-json\/wp\/v2\/media?parent=6238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}